{"id":869,"count":1,"description":"","link":"https:\/\/www.lasocietedesplantes.com\/en\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/balsamine\/","name":"balsamine","slug":"balsamine-3","taxonomy":"product_cat","parent":865,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasocietedesplantes.com\/en\/product-category\/flowering-plants\/ornamental\/annual-ornamentals\/balsamine-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasocietedesplantes.com\/en\/product-category\/flowering-plants\/ornamental\/annual-ornamentals\/balsamine-3\/\" \/>\n<meta property=\"og:site_name\" content=\"LA SOCI\u00c9T\u00c9 DES PLANTES\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lasocietedesplantes.com\/wp-content\/uploads\/2022\/05\/DiaporamaLSDP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/ornementales-annuelles\\\/balsamine\\\/\",\"url\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/ornementales-annuelles\\\/balsamine\\\/\",\"name\":\"balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/ornementales-annuelles\\\/balsamine\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/ornementales-annuelles\\\/balsamine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"plantes \u00e0 fleurs\",\"item\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ornementales\",\"item\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ornementales annuelles\",\"item\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/categorie-produit\\\/plantes-a-fleurs\\\/ornementales\\\/ornementales-annuelles\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"balsamine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#website\",\"url\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/\",\"name\":\"LA SOCI\u00c9T\u00c9 DES PLANTES\",\"description\":\"Semences de vari\u00e9t\u00e9s utiles et agr\u00e9ables\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#organization\",\"name\":\"La soci\u00e9t\u00e9 des plantes\",\"url\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/la-societe-des-plantes-logo-mobile.png\",\"contentUrl\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/la-societe-des-plantes-logo-mobile.png\",\"width\":800,\"height\":313,\"caption\":\"La soci\u00e9t\u00e9 des plantes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lasocietedesplantes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LA-SOCI\u00c9T\u00c9-DES-PLANTES-100844866638607\\\/\",\"https:\\\/\\\/www.instagram.com\\\/la_societe_des_plantes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasocietedesplantes.com\/en\/product-category\/flowering-plants\/ornamental\/annual-ornamentals\/balsamine-3\/","og_locale":"en_US","og_type":"article","og_title":"balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES","og_url":"https:\/\/www.lasocietedesplantes.com\/en\/product-category\/flowering-plants\/ornamental\/annual-ornamentals\/balsamine-3\/","og_site_name":"LA SOCI\u00c9T\u00c9 DES PLANTES","og_image":[{"width":1400,"height":600,"url":"https:\/\/www.lasocietedesplantes.com\/wp-content\/uploads\/2022\/05\/DiaporamaLSDP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/balsamine\/","url":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/balsamine\/","name":"balsamine Archives - LA SOCI\u00c9T\u00c9 DES PLANTES","isPartOf":{"@id":"https:\/\/www.lasocietedesplantes.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/balsamine\/#breadcrumb"},"inLanguage":"en-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/balsamine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lasocietedesplantes.com\/"},{"@type":"ListItem","position":2,"name":"plantes \u00e0 fleurs","item":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/"},{"@type":"ListItem","position":3,"name":"ornementales","item":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/"},{"@type":"ListItem","position":4,"name":"ornementales annuelles","item":"https:\/\/www.lasocietedesplantes.com\/categorie-produit\/plantes-a-fleurs\/ornementales\/ornementales-annuelles\/"},{"@type":"ListItem","position":5,"name":"balsamine"}]},{"@type":"WebSite","@id":"https:\/\/www.lasocietedesplantes.com\/#website","url":"https:\/\/www.lasocietedesplantes.com\/","name":"THE PLANT COMPANY","description":"Seeds of useful and pleasant varieties","publisher":{"@id":"https:\/\/www.lasocietedesplantes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasocietedesplantes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/www.lasocietedesplantes.com\/#organization","name":"The plant company","url":"https:\/\/www.lasocietedesplantes.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/www.lasocietedesplantes.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lasocietedesplantes.com\/wp-content\/uploads\/2022\/02\/la-societe-des-plantes-logo-mobile.png","contentUrl":"https:\/\/www.lasocietedesplantes.com\/wp-content\/uploads\/2022\/02\/la-societe-des-plantes-logo-mobile.png","width":800,"height":313,"caption":"La soci\u00e9t\u00e9 des plantes"},"image":{"@id":"https:\/\/www.lasocietedesplantes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LA-SOCI\u00c9T\u00c9-DES-PLANTES-100844866638607\/","https:\/\/www.instagram.com\/la_societe_des_plantes\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.lasocietedesplantes.com\/en\/wp-json\/wp\/v2\/product_cat\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasocietedesplantes.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.lasocietedesplantes.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.lasocietedesplantes.com\/en\/wp-json\/wp\/v2\/product_cat\/865"}],"wp:post_type":[{"href":"https:\/\/www.lasocietedesplantes.com\/en\/wp-json\/wp\/v2\/product?product_cat=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}